{"id":1673,"date":"2025-11-12T09:44:31","date_gmt":"2025-11-12T09:44:31","guid":{"rendered":"https:\/\/idc-clinic.connectionthemes.com\/especialidades\/implantologia-oral\/"},"modified":"2026-05-12T11:11:34","modified_gmt":"2026-05-12T11:11:34","slug":"implantologie-orale","status":"publish","type":"service","link":"https:\/\/idc.clinic\/fr\/specialites\/implantologie-orale\/","title":{"rendered":"Implantologie Orale"},"content":{"rendered":"","protected":false},"featured_media":1674,"parent":0,"menu_order":3,"template":"","specialties":[34],"class_list":["post-1673","service","type-service","status-publish","has-post-thumbnail","hentry","specialties-dentaria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Implantologie Orale - IDC.Clinic<\/title>\n<meta name=\"description\" content=\"Implantologie orale chez IDC.Clinic : des solutions avanc\u00e9es pour remplacer les dents manquantes avec des implants dentaires s\u00fbrs...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/idc.clinic\/fr\/specialites\/implantologie-orale\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Implantologie Orale - IDC.Clinic\" \/>\n<meta property=\"og:description\" content=\"Implantologie orale chez IDC.Clinic : des solutions avanc\u00e9es pour remplacer les dents manquantes avec des implants dentaires s\u00fbrs...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/idc.clinic\/fr\/specialites\/implantologie-orale\/\" \/>\n<meta property=\"og:site_name\" content=\"IDC.Clinic\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T11:11:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/idc.clinic\/wp-content\/uploads\/2025\/11\/01_Implantologia-Oral.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1064\" \/>\n\t<meta property=\"og:image:height\" content=\"510\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/idc.clinic\\\/fr\\\/specialites\\\/implantologie-orale\\\/\",\"url\":\"https:\\\/\\\/idc.clinic\\\/fr\\\/specialites\\\/implantologie-orale\\\/\",\"name\":\"Implantologie Orale - IDC.Clinic\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/idc.clinic\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/idc.clinic\\\/fr\\\/specialites\\\/implantologie-orale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/idc.clinic\\\/fr\\\/specialites\\\/implantologie-orale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/idc.clinic\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/01_Implantologia-Oral.jpg\",\"datePublished\":\"2025-11-12T09:44:31+00:00\",\"dateModified\":\"2026-05-12T11:11:34+00:00\",\"description\":\"Implantologie orale chez IDC.Clinic : des solutions avanc\u00e9es pour remplacer les dents manquantes avec des implants dentaires s\u00fbrs...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/idc.clinic\\\/fr\\\/specialites\\\/implantologie-orale\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/idc.clinic\\\/fr\\\/specialites\\\/implantologie-orale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/idc.clinic\\\/fr\\\/specialites\\\/implantologie-orale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/idc.clinic\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/01_Implantologia-Oral.jpg\",\"contentUrl\":\"https:\\\/\\\/idc.clinic\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/01_Implantologia-Oral.jpg\",\"width\":1064,\"height\":510},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/idc.clinic\\\/fr\\\/specialites\\\/implantologie-orale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/idc.clinic\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Implantologie Orale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/idc.clinic\\\/#website\",\"url\":\"https:\\\/\\\/idc.clinic\\\/\",\"name\":\"idc\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/idc.clinic\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/idc.clinic\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/idc.clinic\\\/#organization\",\"name\":\"idc\",\"url\":\"https:\\\/\\\/idc.clinic\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/idc.clinic\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/idc.clinic\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/new-logo.png\",\"contentUrl\":\"https:\\\/\\\/idc.clinic\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/new-logo.png\",\"width\":1650,\"height\":686,\"caption\":\"idc\"},\"image\":{\"@id\":\"https:\\\/\\\/idc.clinic\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Implantologie Orale - IDC.Clinic","description":"Implantologie orale chez IDC.Clinic : des solutions avanc\u00e9es pour remplacer les dents manquantes avec des implants dentaires s\u00fbrs...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/idc.clinic\/fr\/specialites\/implantologie-orale\/","og_locale":"fr_FR","og_type":"article","og_title":"Implantologie Orale - IDC.Clinic","og_description":"Implantologie orale chez IDC.Clinic : des solutions avanc\u00e9es pour remplacer les dents manquantes avec des implants dentaires s\u00fbrs...","og_url":"https:\/\/idc.clinic\/fr\/specialites\/implantologie-orale\/","og_site_name":"IDC.Clinic","article_modified_time":"2026-05-12T11:11:34+00:00","og_image":[{"width":1064,"height":510,"url":"https:\/\/idc.clinic\/wp-content\/uploads\/2025\/11\/01_Implantologia-Oral.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/idc.clinic\/fr\/specialites\/implantologie-orale\/","url":"https:\/\/idc.clinic\/fr\/specialites\/implantologie-orale\/","name":"Implantologie Orale - IDC.Clinic","isPartOf":{"@id":"https:\/\/idc.clinic\/#website"},"primaryImageOfPage":{"@id":"https:\/\/idc.clinic\/fr\/specialites\/implantologie-orale\/#primaryimage"},"image":{"@id":"https:\/\/idc.clinic\/fr\/specialites\/implantologie-orale\/#primaryimage"},"thumbnailUrl":"https:\/\/idc.clinic\/wp-content\/uploads\/2025\/11\/01_Implantologia-Oral.jpg","datePublished":"2025-11-12T09:44:31+00:00","dateModified":"2026-05-12T11:11:34+00:00","description":"Implantologie orale chez IDC.Clinic : des solutions avanc\u00e9es pour remplacer les dents manquantes avec des implants dentaires s\u00fbrs...","breadcrumb":{"@id":"https:\/\/idc.clinic\/fr\/specialites\/implantologie-orale\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/idc.clinic\/fr\/specialites\/implantologie-orale\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/idc.clinic\/fr\/specialites\/implantologie-orale\/#primaryimage","url":"https:\/\/idc.clinic\/wp-content\/uploads\/2025\/11\/01_Implantologia-Oral.jpg","contentUrl":"https:\/\/idc.clinic\/wp-content\/uploads\/2025\/11\/01_Implantologia-Oral.jpg","width":1064,"height":510},{"@type":"BreadcrumbList","@id":"https:\/\/idc.clinic\/fr\/specialites\/implantologie-orale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/idc.clinic\/fr\/"},{"@type":"ListItem","position":2,"name":"Implantologie Orale"}]},{"@type":"WebSite","@id":"https:\/\/idc.clinic\/#website","url":"https:\/\/idc.clinic\/","name":"idc","description":"","publisher":{"@id":"https:\/\/idc.clinic\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/idc.clinic\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/idc.clinic\/#organization","name":"idc","url":"https:\/\/idc.clinic\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/idc.clinic\/#\/schema\/logo\/image\/","url":"https:\/\/idc.clinic\/wp-content\/uploads\/2026\/02\/new-logo.png","contentUrl":"https:\/\/idc.clinic\/wp-content\/uploads\/2026\/02\/new-logo.png","width":1650,"height":686,"caption":"idc"},"image":{"@id":"https:\/\/idc.clinic\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/idc.clinic\/fr\/wp-json\/wp\/v2\/service\/1673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/idc.clinic\/fr\/wp-json\/wp\/v2\/service"}],"about":[{"href":"https:\/\/idc.clinic\/fr\/wp-json\/wp\/v2\/types\/service"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/idc.clinic\/fr\/wp-json\/wp\/v2\/media\/1674"}],"wp:attachment":[{"href":"https:\/\/idc.clinic\/fr\/wp-json\/wp\/v2\/media?parent=1673"}],"wp:term":[{"taxonomy":"specialties","embeddable":true,"href":"https:\/\/idc.clinic\/fr\/wp-json\/wp\/v2\/specialties?post=1673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}